{"id":31948,"date":"2024-10-15T19:44:49","date_gmt":"2024-10-15T17:44:49","guid":{"rendered":"https:\/\/mail.cyclingoriginals.com\/?post_type=product&#038;p=31948"},"modified":"2026-08-06T16:27:23","modified_gmt":"2026-08-06T14:27:23","slug":"camisa-ciclismo-spago-3","status":"publish","type":"product","link":"https:\/\/mail.cyclingoriginals.com\/pt\/retro-wielershirt\/belkin-bianchi-2014\/","title":{"rendered":"BELKIN BIANCHI 2014"},"content":{"rendered":"<p>Oferecida para troca esta linda camisa BELKIN-BIANCHI de 2014.<\/p>\n<p>TAMANHO L.<\/p>\n<p>Interessado em uma troca?? Envie um e-mail para: tonmerckx@live.nl<\/p>","protected":false},"excerpt":{"rendered":"<p>Oferecida para troca esta linda camisa BELKIN-BIANCHI de 2014. TAMANHO L. Interessado em trocar?? Envie um e-mail para: tonmerckx@live.nl<\/p>","protected":false},"featured_media":31949,"template":"","meta":[],"product_brand":[],"product_cat":[1402],"product_tag":[],"class_list":["post-31948","product","type-product","status-publish","has-post-thumbnail","product_cat-dubbele-shirts","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BELKIN-BIANCHI 2014 - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mail.cycling-originals.com\/de\/retro-radtrikot\/radtrikot-spago-3\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BELKIN-BIANCHI 2014 - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"og:description\" content=\"Te ruil aangeboden dit mooie BELKIN-BIANCHI\u00a0 shirt uit 2014. MAAT L. Geinteresseerd in een ruil ??\u00a0 Stuur een mailtje naar : tonmerckx@live.nl\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mail.cycling-originals.com\/de\/retro-radtrikot\/radtrikot-spago-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-06T14:27:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2024\/10\/IMG_3180-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/de\\\/retro-radtrikot\\\/radtrikot-spago-3\\\/\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/de\\\/retro-radtrikot\\\/radtrikot-spago-3\\\/\",\"name\":\"BELKIN-BIANCHI 2014 - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tonmerckxwielershirts.nl\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/de\\\/retro-radtrikot\\\/radtrikot-spago-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/de\\\/retro-radtrikot\\\/radtrikot-spago-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/IMG_3180-scaled.jpg\",\"datePublished\":\"2024-10-15T17:44:49+00:00\",\"dateModified\":\"2026-08-06T14:27:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/de\\\/retro-radtrikot\\\/radtrikot-spago-3\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mail.cycling-originals.com\\\/de\\\/retro-radtrikot\\\/radtrikot-spago-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/de\\\/retro-radtrikot\\\/radtrikot-spago-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/IMG_3180-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/IMG_3180-scaled.jpg\",\"width\":1920,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/de\\\/retro-radtrikot\\\/radtrikot-spago-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tonmerckxwielershirts.nl\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retro wielershirts\",\"item\":\"https:\\\/\\\/www.tonmerckxwielershirts.nl\\\/de\\\/retro-radtrikots\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BELKIN-BIANCHI 2014\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tonmerckxwielershirts.nl\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.tonmerckxwielershirts.nl\\\/de\\\/\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"description\":\"thousands of original cycling jerseys - order your replica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tonmerckxwielershirts.nl\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tonmerckxwielershirts.nl\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tonmerckxwielershirts.nl\\\/de\\\/#organization\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"url\":\"https:\\\/\\\/www.tonmerckxwielershirts.nl\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.tonmerckxwielershirts.nl\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"width\":391,\"height\":57,\"caption\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tonmerckxwielershirts.nl\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BELKIN-BIANCHI 2014 - Camisas de Ciclismo Ton Merckx - Uma viagem pelo mundo das camisas de ciclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mail.cycling-originals.com\/de\/retro-radtrikot\/radtrikot-spago-3\/","og_locale":"pt_PT","og_type":"article","og_title":"BELKIN-BIANCHI 2014 - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","og_description":"Te ruil aangeboden dit mooie BELKIN-BIANCHI\u00a0 shirt uit 2014. MAAT L. Geinteresseerd in een ruil ??\u00a0 Stuur een mailtje naar : tonmerckx@live.nl","og_url":"https:\/\/mail.cycling-originals.com\/de\/retro-radtrikot\/radtrikot-spago-3\/","og_site_name":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","article_modified_time":"2026-08-06T14:27:23+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2024\/10\/IMG_3180-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mail.cycling-originals.com\/de\/retro-radtrikot\/radtrikot-spago-3\/","url":"https:\/\/mail.cycling-originals.com\/de\/retro-radtrikot\/radtrikot-spago-3\/","name":"BELKIN-BIANCHI 2014 - Camisas de Ciclismo Ton Merckx - Uma viagem pelo mundo das camisas de ciclismo","isPartOf":{"@id":"https:\/\/www.tonmerckxwielershirts.nl\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mail.cycling-originals.com\/de\/retro-radtrikot\/radtrikot-spago-3\/#primaryimage"},"image":{"@id":"https:\/\/mail.cycling-originals.com\/de\/retro-radtrikot\/radtrikot-spago-3\/#primaryimage"},"thumbnailUrl":"https:\/\/mail.cyclingoriginals.com\/wp-content\/uploads\/2024\/10\/IMG_3180-scaled.jpg","datePublished":"2024-10-15T17:44:49+00:00","dateModified":"2026-08-06T14:27:23+00:00","breadcrumb":{"@id":"https:\/\/mail.cycling-originals.com\/de\/retro-radtrikot\/radtrikot-spago-3\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mail.cycling-originals.com\/de\/retro-radtrikot\/radtrikot-spago-3\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/mail.cycling-originals.com\/de\/retro-radtrikot\/radtrikot-spago-3\/#primaryimage","url":"https:\/\/mail.cyclingoriginals.com\/wp-content\/uploads\/2024\/10\/IMG_3180-scaled.jpg","contentUrl":"https:\/\/mail.cyclingoriginals.com\/wp-content\/uploads\/2024\/10\/IMG_3180-scaled.jpg","width":1920,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/mail.cycling-originals.com\/de\/retro-radtrikot\/radtrikot-spago-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tonmerckxwielershirts.nl\/de\/"},{"@type":"ListItem","position":2,"name":"Retro wielershirts","item":"https:\/\/www.tonmerckxwielershirts.nl\/de\/retro-radtrikots\/"},{"@type":"ListItem","position":3,"name":"BELKIN-BIANCHI 2014"}]},{"@type":"WebSite","@id":"https:\/\/www.tonmerckxwielershirts.nl\/de\/#website","url":"https:\/\/www.tonmerckxwielershirts.nl\/de\/","name":"Camisas de ciclismo Ton Merckx - Tour pelo mundo das camisas de ciclismo","description":"milhares de camisas de ciclismo originais - encomende a sua r\u00e9plica!","publisher":{"@id":"https:\/\/www.tonmerckxwielershirts.nl\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tonmerckxwielershirts.nl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.tonmerckxwielershirts.nl\/de\/#organization","name":"Camisas de ciclismo Ton Merckx - Tour pelo mundo das camisas de ciclismo","url":"https:\/\/www.tonmerckxwielershirts.nl\/de\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.tonmerckxwielershirts.nl\/de\/#\/schema\/logo\/image\/","url":"https:\/\/mail.cyclingoriginals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","contentUrl":"https:\/\/mail.cyclingoriginals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","width":391,"height":57,"caption":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts"},"image":{"@id":"https:\/\/www.tonmerckxwielershirts.nl\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mail.cyclingoriginals.com\/pt\/wp-json\/wp\/v2\/product\/31948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mail.cyclingoriginals.com\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mail.cyclingoriginals.com\/pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mail.cyclingoriginals.com\/pt\/wp-json\/wp\/v2\/media\/31949"}],"wp:attachment":[{"href":"https:\/\/mail.cyclingoriginals.com\/pt\/wp-json\/wp\/v2\/media?parent=31948"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mail.cyclingoriginals.com\/pt\/wp-json\/wp\/v2\/product_brand?post=31948"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mail.cyclingoriginals.com\/pt\/wp-json\/wp\/v2\/product_cat?post=31948"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mail.cyclingoriginals.com\/pt\/wp-json\/wp\/v2\/product_tag?post=31948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}