{"id":3777,"date":"2023-01-24T18:06:36","date_gmt":"2023-01-24T18:06:36","guid":{"rendered":"https:\/\/ton.connectingminds.net\/product\/line-lloyd\/"},"modified":"2026-06-07T16:24:13","modified_gmt":"2026-06-07T14:24:13","slug":"linea-lloyd","status":"publish","type":"product","link":"https:\/\/mail.cyclingoriginals.com\/it\/retro-wielershirt\/line-lloyd\/","title":{"rendered":"LINE-LLOYD CALZATURE CICLISMO 2007 MAGLIA CICLISMO"},"content":{"rendered":"<p>LINE-LLOYD CALZATURE DA CICLISMO 2007<\/p>","protected":false},"excerpt":{"rendered":"<p>LINE-LLOYD CALZATURE DA CICLISMO 2007<\/p>","protected":false},"featured_media":188195,"template":"","meta":[],"product_brand":[],"product_cat":[151],"product_tag":[],"class_list":["post-3777","product","type-product","status-publish","has-post-thumbnail","product_cat-pro-team","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LINE-LLOYD FOOTWEAR CYCLING  2007  WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mail.cyclingoriginals.com\/it\/maglia-da-ciclismo-retro\/linea-lloyd\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LINE-LLOYD FOOTWEAR CYCLING  2007  WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"og:description\" content=\"LINE-LLOYD FOOTWEAR CYCLING 2007\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mail.cyclingoriginals.com\/it\/maglia-da-ciclismo-retro\/linea-lloyd\/\" \/>\n<meta property=\"og:site_name\" content=\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-07T14:24:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mail.cyclingoriginals.com\/wp-content\/uploads\/2023\/01\/029-3-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/retro-wielershirt\\\/line-lloyd\\\/\",\"url\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/retro-wielershirt\\\/line-lloyd\\\/\",\"name\":\"LINE-LLOYD FOOTWEAR CYCLING 2007 WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/retro-wielershirt\\\/line-lloyd\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/retro-wielershirt\\\/line-lloyd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/029-3-scaled.jpg\",\"datePublished\":\"2023-01-24T18:06:36+00:00\",\"dateModified\":\"2026-06-07T14:24:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/retro-wielershirt\\\/line-lloyd\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mail.cyclingoriginals.com\\\/retro-wielershirt\\\/line-lloyd\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/retro-wielershirt\\\/line-lloyd\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/029-3-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/029-3-scaled.jpg\",\"width\":1920,\"height\":2560,\"caption\":\"LINE-LLOYD FOOTWEAR CYCLING 2007\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/retro-wielershirt\\\/line-lloyd\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tonmerckxwielershirts.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retro wielershirts\",\"item\":\"https:\\\/\\\/tonmerckxwielershirts.nl\\\/retro-wielershirts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"LINE-LLOYD FOOTWEAR CYCLING 2007 WIELERSHIRT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#website\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"description\":\"thousands of original cycling jerseys - order your replica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#organization\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"width\":391,\"height\":57,\"caption\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LINE-LLOYD FOOTWEAR CYCLING 2007 MAGLIA CICLISMO - Ton Merckx Cycling Jerseys - Tour nel mondo delle maglie da ciclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mail.cyclingoriginals.com\/it\/maglia-da-ciclismo-retro\/linea-lloyd\/","og_locale":"it_IT","og_type":"article","og_title":"LINE-LLOYD FOOTWEAR CYCLING  2007  WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","og_description":"LINE-LLOYD FOOTWEAR CYCLING 2007","og_url":"https:\/\/mail.cyclingoriginals.com\/it\/maglia-da-ciclismo-retro\/linea-lloyd\/","og_site_name":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","article_modified_time":"2026-06-07T14:24:13+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/mail.cyclingoriginals.com\/wp-content\/uploads\/2023\/01\/029-3-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mail.cyclingoriginals.com\/retro-wielershirt\/line-lloyd\/","url":"https:\/\/mail.cyclingoriginals.com\/retro-wielershirt\/line-lloyd\/","name":"LINE-LLOYD FOOTWEAR CYCLING 2007 MAGLIA CICLISMO - Ton Merckx Cycling Jerseys - Tour nel mondo delle maglie da ciclismo","isPartOf":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mail.cyclingoriginals.com\/retro-wielershirt\/line-lloyd\/#primaryimage"},"image":{"@id":"https:\/\/mail.cyclingoriginals.com\/retro-wielershirt\/line-lloyd\/#primaryimage"},"thumbnailUrl":"https:\/\/mail.cyclingoriginals.com\/wp-content\/uploads\/2023\/01\/029-3-scaled.jpg","datePublished":"2023-01-24T18:06:36+00:00","dateModified":"2026-06-07T14:24:13+00:00","breadcrumb":{"@id":"https:\/\/mail.cyclingoriginals.com\/retro-wielershirt\/line-lloyd\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mail.cyclingoriginals.com\/retro-wielershirt\/line-lloyd\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/mail.cyclingoriginals.com\/retro-wielershirt\/line-lloyd\/#primaryimage","url":"https:\/\/mail.cyclingoriginals.com\/wp-content\/uploads\/2023\/01\/029-3-scaled.jpg","contentUrl":"https:\/\/mail.cyclingoriginals.com\/wp-content\/uploads\/2023\/01\/029-3-scaled.jpg","width":1920,"height":2560,"caption":"LINE-LLOYD FOOTWEAR CYCLING 2007"},{"@type":"BreadcrumbList","@id":"https:\/\/mail.cyclingoriginals.com\/retro-wielershirt\/line-lloyd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tonmerckxwielershirts.nl\/"},{"@type":"ListItem","position":2,"name":"Retro wielershirts","item":"https:\/\/tonmerckxwielershirts.nl\/retro-wielershirts\/"},{"@type":"ListItem","position":3,"name":"LINE-LLOYD FOOTWEAR CYCLING 2007 WIELERSHIRT"}]},{"@type":"WebSite","@id":"https:\/\/mail.replica-cycling.com\/ja\/#website","url":"https:\/\/mail.replica-cycling.com\/ja\/","name":"Magliette da ciclismo Ton Merckx - Tour nel mondo delle magliette da ciclismo","description":"migliaia di maglie da ciclismo originali - ordina la tua replica!","publisher":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.replica-cycling.com\/ja\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/mail.replica-cycling.com\/ja\/#organization","name":"Magliette da ciclismo Ton Merckx - Tour nel mondo delle magliette da ciclismo","url":"https:\/\/mail.replica-cycling.com\/ja\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/mail.replica-cycling.com\/ja\/#\/schema\/logo\/image\/","url":"https:\/\/mail.cyclingoriginals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","contentUrl":"https:\/\/mail.cyclingoriginals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","width":391,"height":57,"caption":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts"},"image":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mail.cyclingoriginals.com\/it\/wp-json\/wp\/v2\/product\/3777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mail.cyclingoriginals.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mail.cyclingoriginals.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mail.cyclingoriginals.com\/it\/wp-json\/wp\/v2\/media\/188195"}],"wp:attachment":[{"href":"https:\/\/mail.cyclingoriginals.com\/it\/wp-json\/wp\/v2\/media?parent=3777"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mail.cyclingoriginals.com\/it\/wp-json\/wp\/v2\/product_brand?post=3777"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mail.cyclingoriginals.com\/it\/wp-json\/wp\/v2\/product_cat?post=3777"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mail.cyclingoriginals.com\/it\/wp-json\/wp\/v2\/product_tag?post=3777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}