{"id":2762,"date":"2023-01-24T17:53:57","date_gmt":"2023-01-24T17:53:57","guid":{"rendered":"https:\/\/ton.connectingminds.net\/product\/puch-campagnolo-wolber-2\/"},"modified":"2026-05-13T15:38:40","modified_gmt":"2026-05-13T13:38:40","slug":"puch-campagnolo-wolber-2","status":"publish","type":"product","link":"https:\/\/mail.cyclingoriginals.com\/it\/retro-wielershirt\/puch-campagnolo-wolber-2\/","title":{"rendered":"MAGLIA CICLISMO PUCH (c)-CAMPAGNOLO-WOLBER 1981"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":2761,"template":"","meta":[],"product_brand":[],"product_cat":[151],"product_tag":[],"class_list":["post-2762","product","type-product","status-publish","has-post-thumbnail","product_cat-pro-team","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PUCH (c)-CAMPAGNOLO-WOLBER  1981   WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mail.cyclingoriginals.com\/it\/maglia-da-ciclismo-retro\/puch-campagnolo-wolber-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PUCH (c)-CAMPAGNOLO-WOLBER  1981   WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mail.cyclingoriginals.com\/it\/maglia-da-ciclismo-retro\/puch-campagnolo-wolber-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T13:38:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mail.cyclingoriginals.com\/wp-content\/uploads\/2023\/01\/SSA43529.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1704\" \/>\n\t<meta property=\"og:image:height\" content=\"2272\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/fr\\\/maillot-de-cyclisme-retro\\\/puch-campagnolo-wolber-2\\\/\",\"url\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/fr\\\/maillot-de-cyclisme-retro\\\/puch-campagnolo-wolber-2\\\/\",\"name\":\"PUCH (c)-CAMPAGNOLO-WOLBER 1981 WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/fr\\\/maillot-de-cyclisme-retro\\\/puch-campagnolo-wolber-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/fr\\\/maillot-de-cyclisme-retro\\\/puch-campagnolo-wolber-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SSA43529.jpg\",\"datePublished\":\"2023-01-24T17:53:57+00:00\",\"dateModified\":\"2026-05-13T13:38:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/fr\\\/maillot-de-cyclisme-retro\\\/puch-campagnolo-wolber-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mail.cyclingoriginals.com\\\/fr\\\/maillot-de-cyclisme-retro\\\/puch-campagnolo-wolber-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/fr\\\/maillot-de-cyclisme-retro\\\/puch-campagnolo-wolber-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SSA43529.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SSA43529.jpg\",\"width\":1704,\"height\":2272},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/fr\\\/maillot-de-cyclisme-retro\\\/puch-campagnolo-wolber-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tonmerckxwielershirts.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retro wielershirts\",\"item\":\"https:\\\/\\\/tonmerckxwielershirts.nl\\\/retro-wielershirts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"PUCH (c)-CAMPAGNOLO-WOLBER 1981 WIELERSHIRT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#website\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"description\":\"thousands of original cycling jerseys - order your replica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#organization\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"width\":391,\"height\":57,\"caption\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MAGLIA CICLISMO PUCH (c)-CAMPAGNOLO-WOLBER 1981 - Maglie ciclismo Ton Merckx - Viaggio nel mondo delle maglie ciclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mail.cyclingoriginals.com\/it\/maglia-da-ciclismo-retro\/puch-campagnolo-wolber-2\/","og_locale":"it_IT","og_type":"article","og_title":"PUCH (c)-CAMPAGNOLO-WOLBER  1981   WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","og_url":"https:\/\/mail.cyclingoriginals.com\/it\/maglia-da-ciclismo-retro\/puch-campagnolo-wolber-2\/","og_site_name":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","article_modified_time":"2026-05-13T13:38:40+00:00","og_image":[{"width":1704,"height":2272,"url":"https:\/\/mail.cyclingoriginals.com\/wp-content\/uploads\/2023\/01\/SSA43529.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mail.cyclingoriginals.com\/fr\/maillot-de-cyclisme-retro\/puch-campagnolo-wolber-2\/","url":"https:\/\/mail.cyclingoriginals.com\/fr\/maillot-de-cyclisme-retro\/puch-campagnolo-wolber-2\/","name":"MAGLIA CICLISMO PUCH (c)-CAMPAGNOLO-WOLBER 1981 - Maglie ciclismo Ton Merckx - Viaggio nel mondo delle maglie ciclismo","isPartOf":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mail.cyclingoriginals.com\/fr\/maillot-de-cyclisme-retro\/puch-campagnolo-wolber-2\/#primaryimage"},"image":{"@id":"https:\/\/mail.cyclingoriginals.com\/fr\/maillot-de-cyclisme-retro\/puch-campagnolo-wolber-2\/#primaryimage"},"thumbnailUrl":"https:\/\/mail.cyclingoriginals.com\/wp-content\/uploads\/2023\/01\/SSA43529.jpg","datePublished":"2023-01-24T17:53:57+00:00","dateModified":"2026-05-13T13:38:40+00:00","breadcrumb":{"@id":"https:\/\/mail.cyclingoriginals.com\/fr\/maillot-de-cyclisme-retro\/puch-campagnolo-wolber-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mail.cyclingoriginals.com\/fr\/maillot-de-cyclisme-retro\/puch-campagnolo-wolber-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/mail.cyclingoriginals.com\/fr\/maillot-de-cyclisme-retro\/puch-campagnolo-wolber-2\/#primaryimage","url":"https:\/\/mail.cyclingoriginals.com\/wp-content\/uploads\/2023\/01\/SSA43529.jpg","contentUrl":"https:\/\/mail.cyclingoriginals.com\/wp-content\/uploads\/2023\/01\/SSA43529.jpg","width":1704,"height":2272},{"@type":"BreadcrumbList","@id":"https:\/\/mail.cyclingoriginals.com\/fr\/maillot-de-cyclisme-retro\/puch-campagnolo-wolber-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tonmerckxwielershirts.nl\/"},{"@type":"ListItem","position":2,"name":"Retro wielershirts","item":"https:\/\/tonmerckxwielershirts.nl\/retro-wielershirts\/"},{"@type":"ListItem","position":3,"name":"PUCH (c)-CAMPAGNOLO-WOLBER 1981 WIELERSHIRT"}]},{"@type":"WebSite","@id":"https:\/\/mail.replica-cycling.com\/ja\/#website","url":"https:\/\/mail.replica-cycling.com\/ja\/","name":"Magliette da ciclismo Ton Merckx - Tour nel mondo delle magliette da ciclismo","description":"migliaia di maglie da ciclismo originali - ordina la tua replica!","publisher":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.replica-cycling.com\/ja\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/mail.replica-cycling.com\/ja\/#organization","name":"Magliette da ciclismo Ton Merckx - Tour nel mondo delle magliette da ciclismo","url":"https:\/\/mail.replica-cycling.com\/ja\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/mail.replica-cycling.com\/ja\/#\/schema\/logo\/image\/","url":"https:\/\/mail.cyclingoriginals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","contentUrl":"https:\/\/mail.cyclingoriginals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","width":391,"height":57,"caption":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts"},"image":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mail.cyclingoriginals.com\/it\/wp-json\/wp\/v2\/product\/2762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mail.cyclingoriginals.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mail.cyclingoriginals.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mail.cyclingoriginals.com\/it\/wp-json\/wp\/v2\/media\/2761"}],"wp:attachment":[{"href":"https:\/\/mail.cyclingoriginals.com\/it\/wp-json\/wp\/v2\/media?parent=2762"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mail.cyclingoriginals.com\/it\/wp-json\/wp\/v2\/product_brand?post=2762"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mail.cyclingoriginals.com\/it\/wp-json\/wp\/v2\/product_cat?post=2762"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mail.cyclingoriginals.com\/it\/wp-json\/wp\/v2\/product_tag?post=2762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}