{"id":5086,"date":"2023-01-24T18:23:10","date_gmt":"2023-01-24T18:23:10","guid":{"rendered":"https:\/\/ton.connectingminds.net\/product\/us-postal-service-trek-3\/"},"modified":"2026-08-06T16:27:36","modified_gmt":"2026-08-06T14:27:36","slug":"service-postal-americain-tirage-3","status":"publish","type":"product","link":"https:\/\/mail.cyclingoriginals.com\/fr\/retro-wielershirt\/us-postal-service-trek-3\/","title":{"rendered":"SERVICE POSTAL AM\u00c9RICAIN (e)-CHEMISE DE CYCLISME TREK-VISA 1999"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":5085,"template":"","meta":[],"product_brand":[],"product_cat":[151],"product_tag":[],"class_list":["post-5086","product","type-product","status-publish","has-post-thumbnail","product_cat-pro-team","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>US POSTAL SERVICE (e)-TREK-VISA  1999  WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mail.cyclingoriginals.com\/fr\/maillot-de-cyclisme-retro\/service-postal-americain-tirage-3\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"US POSTAL SERVICE (e)-TREK-VISA  1999  WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mail.cyclingoriginals.com\/fr\/maillot-de-cyclisme-retro\/service-postal-americain-tirage-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-06T14:27:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mail.cyclingoriginals.com\/wp-content\/uploads\/2023\/01\/SSA43879.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1704\" \/>\n\t<meta property=\"og:image:height\" content=\"2272\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/de\\\/retro-radtrikot\\\/us-postdienst-pull-3\\\/\",\"url\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/de\\\/retro-radtrikot\\\/us-postdienst-pull-3\\\/\",\"name\":\"US POSTAL SERVICE (e)-TREK-VISA 1999 WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tonmerckxwielershirts.nl\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/de\\\/retro-radtrikot\\\/us-postdienst-pull-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/de\\\/retro-radtrikot\\\/us-postdienst-pull-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SSA43879.jpg\",\"datePublished\":\"2023-01-24T18:23:10+00:00\",\"dateModified\":\"2026-08-06T14:27:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/de\\\/retro-radtrikot\\\/us-postdienst-pull-3\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mail.cyclingoriginals.com\\\/de\\\/retro-radtrikot\\\/us-postdienst-pull-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/de\\\/retro-radtrikot\\\/us-postdienst-pull-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SSA43879.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SSA43879.jpg\",\"width\":1704,\"height\":2272},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/de\\\/retro-radtrikot\\\/us-postdienst-pull-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tonmerckxwielershirts.nl\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retro wielershirts\",\"item\":\"https:\\\/\\\/www.tonmerckxwielershirts.nl\\\/de\\\/retro-radtrikots\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"US POSTAL SERVICE (e)-TREK-VISA 1999 WIELERSHIRT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tonmerckxwielershirts.nl\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.tonmerckxwielershirts.nl\\\/de\\\/\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"description\":\"thousands of original cycling jerseys - order your replica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tonmerckxwielershirts.nl\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tonmerckxwielershirts.nl\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tonmerckxwielershirts.nl\\\/de\\\/#organization\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"url\":\"https:\\\/\\\/www.tonmerckxwielershirts.nl\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.tonmerckxwielershirts.nl\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"width\":391,\"height\":57,\"caption\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tonmerckxwielershirts.nl\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"US POSTAL SERVICE (e)-TREK-VISA 1999 CYCLING SHIRT - Ton Merckx Cycling Jerseys - Tour \u00e0 travers le monde des maillots de cyclisme","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mail.cyclingoriginals.com\/fr\/maillot-de-cyclisme-retro\/service-postal-americain-tirage-3\/","og_locale":"fr_FR","og_type":"article","og_title":"US POSTAL SERVICE (e)-TREK-VISA  1999  WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","og_url":"https:\/\/mail.cyclingoriginals.com\/fr\/maillot-de-cyclisme-retro\/service-postal-americain-tirage-3\/","og_site_name":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","article_modified_time":"2026-08-06T14:27:36+00:00","og_image":[{"width":1704,"height":2272,"url":"https:\/\/mail.cyclingoriginals.com\/wp-content\/uploads\/2023\/01\/SSA43879.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mail.cyclingoriginals.com\/de\/retro-radtrikot\/us-postdienst-pull-3\/","url":"https:\/\/mail.cyclingoriginals.com\/de\/retro-radtrikot\/us-postdienst-pull-3\/","name":"US POSTAL SERVICE (e)-TREK-VISA 1999 CYCLING SHIRT - Ton Merckx Cycling Jerseys - Tour \u00e0 travers le monde des maillots de cyclisme","isPartOf":{"@id":"https:\/\/www.tonmerckxwielershirts.nl\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mail.cyclingoriginals.com\/de\/retro-radtrikot\/us-postdienst-pull-3\/#primaryimage"},"image":{"@id":"https:\/\/mail.cyclingoriginals.com\/de\/retro-radtrikot\/us-postdienst-pull-3\/#primaryimage"},"thumbnailUrl":"https:\/\/mail.cyclingoriginals.com\/wp-content\/uploads\/2023\/01\/SSA43879.jpg","datePublished":"2023-01-24T18:23:10+00:00","dateModified":"2026-08-06T14:27:36+00:00","breadcrumb":{"@id":"https:\/\/mail.cyclingoriginals.com\/de\/retro-radtrikot\/us-postdienst-pull-3\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mail.cyclingoriginals.com\/de\/retro-radtrikot\/us-postdienst-pull-3\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mail.cyclingoriginals.com\/de\/retro-radtrikot\/us-postdienst-pull-3\/#primaryimage","url":"https:\/\/mail.cyclingoriginals.com\/wp-content\/uploads\/2023\/01\/SSA43879.jpg","contentUrl":"https:\/\/mail.cyclingoriginals.com\/wp-content\/uploads\/2023\/01\/SSA43879.jpg","width":1704,"height":2272},{"@type":"BreadcrumbList","@id":"https:\/\/mail.cyclingoriginals.com\/de\/retro-radtrikot\/us-postdienst-pull-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tonmerckxwielershirts.nl\/de\/"},{"@type":"ListItem","position":2,"name":"Retro wielershirts","item":"https:\/\/www.tonmerckxwielershirts.nl\/de\/retro-radtrikots\/"},{"@type":"ListItem","position":3,"name":"US POSTAL SERVICE (e)-TREK-VISA 1999 WIELERSHIRT"}]},{"@type":"WebSite","@id":"https:\/\/www.tonmerckxwielershirts.nl\/de\/#website","url":"https:\/\/www.tonmerckxwielershirts.nl\/de\/","name":"Chemises de cyclisme Ton Merckx - Tour \u00e0 travers le monde des chemises de cyclisme","description":"des milliers de maillots de cyclisme originaux - commandez votre r\u00e9plique !","publisher":{"@id":"https:\/\/www.tonmerckxwielershirts.nl\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tonmerckxwielershirts.nl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.tonmerckxwielershirts.nl\/de\/#organization","name":"Chemises de cyclisme Ton Merckx - Tour \u00e0 travers le monde des chemises de cyclisme","url":"https:\/\/www.tonmerckxwielershirts.nl\/de\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.tonmerckxwielershirts.nl\/de\/#\/schema\/logo\/image\/","url":"https:\/\/mail.cyclingoriginals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","contentUrl":"https:\/\/mail.cyclingoriginals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","width":391,"height":57,"caption":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts"},"image":{"@id":"https:\/\/www.tonmerckxwielershirts.nl\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mail.cyclingoriginals.com\/fr\/wp-json\/wp\/v2\/product\/5086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mail.cyclingoriginals.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mail.cyclingoriginals.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mail.cyclingoriginals.com\/fr\/wp-json\/wp\/v2\/media\/5085"}],"wp:attachment":[{"href":"https:\/\/mail.cyclingoriginals.com\/fr\/wp-json\/wp\/v2\/media?parent=5086"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mail.cyclingoriginals.com\/fr\/wp-json\/wp\/v2\/product_brand?post=5086"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mail.cyclingoriginals.com\/fr\/wp-json\/wp\/v2\/product_cat?post=5086"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mail.cyclingoriginals.com\/fr\/wp-json\/wp\/v2\/product_tag?post=5086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}